{"id":6715,"date":"2019-02-07T15:50:46","date_gmt":"2019-02-07T14:50:46","guid":{"rendered":"https:\/\/goes.be\/?p=6715\/"},"modified":"2023-10-06T21:41:00","modified_gmt":"2023-10-06T20:41:00","slug":"wij-gebruiken-als-eerste-in-belgie-de-eyhance-lens","status":"publish","type":"post","link":"https:\/\/goes.be\/en\/wij-gebruiken-als-eerste-in-belgie-de-eyhance-lens\/","title":{"rendered":"Goes Oogcentrum introduceert de nieuwste generatie implantlenzen in Belgi\u00eb"},"content":{"rendered":"<h1>Goes Oogcentrum introduceert de nieuwste generatie implantlenzen in Belgi\u00eb<\/h1>\n<p>&nbsp;<\/p>\n<p><strong>Revolutionair nieuws voor cataractpati\u00ebnten! Met de Eyhance lens, de eerste unifocale\u00a0lens in Europa die geproduceerd wordt door <span style=\"color: #49d1d8;\"><a style=\"color: #49d1d8;\" href=\"https:\/\/www.jjvision.com\/\">Johnson en Johnson<\/a><\/span>, is de kans groter dat u weer 10\/10 in de verte kan zien, en dit zonder bril.\u00a0<\/strong><strong>Dr.\u00a0Goes\u00a0van het\u00a0Goes\u00a0OogCentrum had de eer de allereerste Eyhance-lenzen in Belgi\u00eb te mogen implanteren.<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Goes Oogcentrum introduceert de nieuwste generatie implantlenzen in Belgi\u00eb &nbsp;  &#8230;<\/p>","protected":false},"author":11,"featured_media":6721,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-6715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nieuws"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.1 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Wij gebruiken als eerste in Belgi\u00eb de Eyhance lens | Goes Oogcentrum<\/title>\n<meta name=\"description\" content=\"De Eyhance lens verbeterd het middellange zicht en het zicht in de verte. Dr. Frank Goes Jr. was de eerste in Belgi\u00eb die de lens mocht gebruiken.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/goes.be\/en\/wij-gebruiken-als-eerste-in-belgie-de-eyhance-lens\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Goes Oogcentrum introduceert de nieuwste generatie implantlenzen in Belgi\u00eb\" \/>\n<meta property=\"og:description\" content=\"De Eyhance lens verbeterd het middellange zicht en het zicht in de verte. Dr. Frank Goes Jr. was de eerste in Belgi\u00eb die de lens mocht gebruiken.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/goes.be\/en\/wij-gebruiken-als-eerste-in-belgie-de-eyhance-lens\/\" \/>\n<meta property=\"og:site_name\" content=\"Goes Oogcentrum | Ooglaseren in Antwerpen\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-07T14:50:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-06T20:41:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/goes.be\/wp-content\/uploads\/2022\/06\/GoesOogcentrum-Logotype-Standaard.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"131\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Frank Goes Jr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Frank Goes Jr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Wij gebruiken als eerste in Belgi\u00eb de Eyhance lens | Goes Oogcentrum","description":"De Eyhance lens verbeterd het middellange zicht en het zicht in de verte. Dr. Frank Goes Jr. was de eerste in Belgi\u00eb die de lens mocht gebruiken.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/goes.be\/en\/wij-gebruiken-als-eerste-in-belgie-de-eyhance-lens\/","og_locale":"en_GB","og_type":"article","og_title":"Goes Oogcentrum introduceert de nieuwste generatie implantlenzen in Belgi\u00eb","og_description":"De Eyhance lens verbeterd het middellange zicht en het zicht in de verte. Dr. Frank Goes Jr. was de eerste in Belgi\u00eb die de lens mocht gebruiken.","og_url":"https:\/\/goes.be\/en\/wij-gebruiken-als-eerste-in-belgie-de-eyhance-lens\/","og_site_name":"Goes Oogcentrum | Ooglaseren in Antwerpen","article_published_time":"2019-02-07T14:50:46+00:00","article_modified_time":"2023-10-06T20:41:00+00:00","og_image":[{"width":400,"height":131,"url":"https:\/\/goes.be\/wp-content\/uploads\/2022\/06\/GoesOogcentrum-Logotype-Standaard.jpg","type":"image\/jpeg"}],"author":"Frank Goes Jr","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Frank Goes Jr","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/goes.be\/wij-gebruiken-als-eerste-in-belgie-de-eyhance-lens\/#article","isPartOf":{"@id":"https:\/\/goes.be\/wij-gebruiken-als-eerste-in-belgie-de-eyhance-lens\/"},"author":{"name":"Frank Goes Jr","@id":"https:\/\/goes.be\/#\/schema\/person\/6d78173f6ec685bf769b2cc6ff9d69a6"},"headline":"Goes Oogcentrum introduceert de nieuwste generatie implantlenzen in Belgi\u00eb","datePublished":"2019-02-07T14:50:46+00:00","dateModified":"2023-10-06T20:41:00+00:00","mainEntityOfPage":{"@id":"https:\/\/goes.be\/wij-gebruiken-als-eerste-in-belgie-de-eyhance-lens\/"},"wordCount":74,"publisher":{"@id":"https:\/\/goes.be\/#organization"},"image":{"@id":"https:\/\/goes.be\/wij-gebruiken-als-eerste-in-belgie-de-eyhance-lens\/#primaryimage"},"thumbnailUrl":"","articleSection":["Nieuws"],"inLanguage":"en-GB"},{"@type":["WebPage","MedicalWebPage"],"@id":"https:\/\/goes.be\/wij-gebruiken-als-eerste-in-belgie-de-eyhance-lens\/","url":"https:\/\/goes.be\/wij-gebruiken-als-eerste-in-belgie-de-eyhance-lens\/","name":"Wij gebruiken als eerste in Belgi\u00eb de Eyhance lens | Goes Oogcentrum","isPartOf":{"@id":"https:\/\/goes.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/goes.be\/wij-gebruiken-als-eerste-in-belgie-de-eyhance-lens\/#primaryimage"},"image":{"@id":"https:\/\/goes.be\/wij-gebruiken-als-eerste-in-belgie-de-eyhance-lens\/#primaryimage"},"thumbnailUrl":"","datePublished":"2019-02-07T14:50:46+00:00","dateModified":"2023-10-06T20:41:00+00:00","description":"De Eyhance lens verbeterd het middellange zicht en het zicht in de verte. Dr. Frank Goes Jr. was de eerste in Belgi\u00eb die de lens mocht gebruiken.","breadcrumb":{"@id":"https:\/\/goes.be\/wij-gebruiken-als-eerste-in-belgie-de-eyhance-lens\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/goes.be\/wij-gebruiken-als-eerste-in-belgie-de-eyhance-lens\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/goes.be\/wij-gebruiken-als-eerste-in-belgie-de-eyhance-lens\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/goes.be\/wij-gebruiken-als-eerste-in-belgie-de-eyhance-lens\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/goes.be\/"},{"@type":"ListItem","position":2,"name":"Goes Oogcentrum introduceert de nieuwste generatie implantlenzen in Belgi\u00eb"}]},{"@type":"WebSite","@id":"https:\/\/goes.be\/#website","url":"https:\/\/goes.be\/","name":"Goes Oogcentrum | Ooglaseren in Antwerpen","description":"Oogchirurgie en ooglaseren in Antwerpen","publisher":{"@id":"https:\/\/goes.be\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/goes.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/goes.be\/#organization","name":"Goes Oogcentrum","url":"https:\/\/goes.be\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/goes.be\/#\/schema\/logo\/image\/","url":"https:\/\/goes.be\/wp-content\/uploads\/2022\/06\/GoesOogcentrum-Logotype-Standaard.jpg","contentUrl":"https:\/\/goes.be\/wp-content\/uploads\/2022\/06\/GoesOogcentrum-Logotype-Standaard.jpg","width":400,"height":131,"caption":"Goes Oogcentrum"},"image":{"@id":"https:\/\/goes.be\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/goes.be\/#\/schema\/person\/6d78173f6ec685bf769b2cc6ff9d69a6","name":"Frank Goes Jr","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/6146c66c2b494125193d24357cb5eb5f70d9e5b92931a7e934af74ea601fafe5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6146c66c2b494125193d24357cb5eb5f70d9e5b92931a7e934af74ea601fafe5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6146c66c2b494125193d24357cb5eb5f70d9e5b92931a7e934af74ea601fafe5?s=96&d=mm&r=g","caption":"Frank Goes Jr"},"description":"Met meer dan 20 jaar ervaring heb ik het voorrecht om pati\u00ebnten van alle leeftijden hun goede zicht terug te geven of hun goede zicht zo lang mogelijk te behouden. Ik ben en was al meermaals lid van verschillende nationale en internationale verenigingen over oogchirurgie en ooglaser, en ik had al vaak de eer cursussen en voordrachten te mogen geven over cataract- en laserchirurgie. Goede ooglaserbehandelingen en zeer nauwkeurige staaroperaties zijn afhankelijk van de expertise van de zorgverlener. De zorgverlener moet ook toegang hebben tot nauwkeurige gereedschappen. De beste oogchirurgen weten hoe ze de behandeling veilig, comfortabel en positief voor de pati\u00ebnt kunnen maken. Ze weten hoe ze het risico op complicaties kunnen minimaliseren en succesvolle resultaten kunnen maximaliseren.","sameAs":["https:\/\/be.linkedin.com\/in\/frankgoes"],"knowsLanguage":["English","Dutch"],"jobTitle":"Hoofdverantwoordelijke en Oogchirurg","url":"https:\/\/goes.be\/en\/author\/frank-goes-jr\/"}]}},"_links":{"self":[{"href":"https:\/\/goes.be\/en\/wp-json\/wp\/v2\/posts\/6715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goes.be\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/goes.be\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/goes.be\/en\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/goes.be\/en\/wp-json\/wp\/v2\/comments?post=6715"}],"version-history":[{"count":0,"href":"https:\/\/goes.be\/en\/wp-json\/wp\/v2\/posts\/6715\/revisions"}],"wp:attachment":[{"href":"https:\/\/goes.be\/en\/wp-json\/wp\/v2\/media?parent=6715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/goes.be\/en\/wp-json\/wp\/v2\/categories?post=6715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/goes.be\/en\/wp-json\/wp\/v2\/tags?post=6715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}